{"id":1,"count":7,"description":"","link":"https:\/\/www.colegioquimahue.cl\/quimahue\/categorias\/sin-categoria\/","name":"Banner","slug":"sin-categoria","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.colegioquimahue.cl\/quimahue\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colegioquimahue.cl\/quimahue\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.colegioquimahue.cl\/quimahue\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.colegioquimahue.cl\/quimahue\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}